{"id":6393,"count":1,"description":"","link":"https:\/\/www.santpol.edu.es\/ca\/blog\/6389\/","name":"6389","slug":"6389","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>6389 Archivos - EUHT StPOL<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"6389 Archivos - EUHT StPOL\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.santpol.edu.es\/ca\/blog\/6389\/\" \/>\n<meta property=\"og:site_name\" content=\"EUHT StPOL\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@euhtstpol\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.santpol.edu.es\/ca\/blog\/6389\/\",\"url\":\"https:\/\/www.santpol.edu.es\/ca\/blog\/6389\/\",\"name\":\"6389 Archivos - EUHT StPOL\",\"isPartOf\":{\"@id\":\"https:\/\/www.santpol.edu.es\/#website\"},\"inLanguage\":\"ca\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.santpol.edu.es\/#website\",\"url\":\"https:\/\/www.santpol.edu.es\/\",\"name\":\"EUHT StPOL\",\"description\":\"Escuela Universitaria de Hoteler\u00eda y Turismo\",\"publisher\":{\"@id\":\"https:\/\/www.santpol.edu.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.santpol.edu.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.santpol.edu.es\/#organization\",\"name\":\"EUHT StPOL\",\"url\":\"https:\/\/www.santpol.edu.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/www.santpol.edu.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/santpol.edu.es\/wp-content\/uploads\/2019\/09\/logoweb-santpol.jpg\",\"contentUrl\":\"https:\/\/santpol.edu.es\/wp-content\/uploads\/2019\/09\/logoweb-santpol.jpg\",\"width\":324,\"height\":81,\"caption\":\"EUHT StPOL\"},\"image\":{\"@id\":\"https:\/\/www.santpol.edu.es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EUHTStPOL\",\"https:\/\/x.com\/euhtstpol\",\"https:\/\/www.instagram.com\/euhtstpol\/\",\"https:\/\/www.linkedin.com\/school\/euhtstpol-barcelona\/mycompany\/\",\"https:\/\/es.pinterest.com\/euhtstpol\/\",\"https:\/\/www.youtube.com\/user\/EUHTStPOL1\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"6389 Archivos - EUHT StPOL","robots":{"index":"noindex","follow":"follow"},"og_locale":"ca_ES","og_type":"article","og_title":"6389 Archivos - EUHT StPOL","og_url":"https:\/\/www.santpol.edu.es\/ca\/blog\/6389\/","og_site_name":"EUHT StPOL","twitter_card":"summary_large_image","twitter_site":"@euhtstpol","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.santpol.edu.es\/ca\/blog\/6389\/","url":"https:\/\/www.santpol.edu.es\/ca\/blog\/6389\/","name":"6389 Archivos - EUHT StPOL","isPartOf":{"@id":"https:\/\/www.santpol.edu.es\/#website"},"inLanguage":"ca"},{"@type":"WebSite","@id":"https:\/\/www.santpol.edu.es\/#website","url":"https:\/\/www.santpol.edu.es\/","name":"EUHT StPOL","description":"Escuela Universitaria de Hoteler\u00eda y Turismo","publisher":{"@id":"https:\/\/www.santpol.edu.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.santpol.edu.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.santpol.edu.es\/#organization","name":"EUHT StPOL","url":"https:\/\/www.santpol.edu.es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.santpol.edu.es\/#\/schema\/logo\/image\/","url":"https:\/\/santpol.edu.es\/wp-content\/uploads\/2019\/09\/logoweb-santpol.jpg","contentUrl":"https:\/\/santpol.edu.es\/wp-content\/uploads\/2019\/09\/logoweb-santpol.jpg","width":324,"height":81,"caption":"EUHT StPOL"},"image":{"@id":"https:\/\/www.santpol.edu.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EUHTStPOL","https:\/\/x.com\/euhtstpol","https:\/\/www.instagram.com\/euhtstpol\/","https:\/\/www.linkedin.com\/school\/euhtstpol-barcelona\/mycompany\/","https:\/\/es.pinterest.com\/euhtstpol\/","https:\/\/www.youtube.com\/user\/EUHTStPOL1"]}]}},"_links":{"self":[{"href":"https:\/\/www.santpol.edu.es\/ca\/wp-json\/wp\/v2\/tags\/6393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.santpol.edu.es\/ca\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.santpol.edu.es\/ca\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.santpol.edu.es\/ca\/wp-json\/wp\/v2\/posts?tags=6393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}