{"id":9619,"count":0,"description":"","link":"https:\/\/www.santpol.edu.es\/en\/blog\/hotel-savoy-ca-en\/","name":"hotel savoy","slug":"hotel-savoy-ca-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>hotel savoy Archivos - St. POL Hospitality &amp; Culinary Business School - Barcelona<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"hotel savoy Archivos - St. POL Hospitality &amp; Culinary Business School - Barcelona\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.santpol.edu.es\/en\/blog\/hotel-savoy-ca-en\/\" \/>\n<meta property=\"og:site_name\" content=\"St. POL Hospitality &amp; Culinary Business School - Barcelona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@euhtstpol\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.santpol.edu.es\/en\/blog\/hotel-savoy-ca-en\/\",\"url\":\"https:\/\/www.santpol.edu.es\/en\/blog\/hotel-savoy-ca-en\/\",\"name\":\"hotel savoy Archivos - St. POL Hospitality &amp; Culinary Business School - Barcelona\",\"isPartOf\":{\"@id\":\"https:\/\/www.santpol.edu.es\/#website\"},\"inLanguage\":\"en-US\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.santpol.edu.es\/#website\",\"url\":\"https:\/\/www.santpol.edu.es\/\",\"name\":\"St. POL Hospitality &amp; Culinary Business School - Barcelona\",\"description\":\"St. POL Hospitality &amp; Culinary Business School - Barcelona\",\"publisher\":{\"@id\":\"https:\/\/www.santpol.edu.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.santpol.edu.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.santpol.edu.es\/#organization\",\"name\":\"St. POL Hospitality &amp; Culinary Business School - Barcelona\",\"url\":\"https:\/\/www.santpol.edu.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.santpol.edu.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/santpol.edu.es\/wp-content\/uploads\/2019\/09\/logoweb-santpol.jpg\",\"contentUrl\":\"https:\/\/santpol.edu.es\/wp-content\/uploads\/2019\/09\/logoweb-santpol.jpg\",\"width\":324,\"height\":81,\"caption\":\"St. POL Hospitality &amp; Culinary Business School - Barcelona\"},\"image\":{\"@id\":\"https:\/\/www.santpol.edu.es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EUHTStPOL\",\"https:\/\/x.com\/euhtstpol\",\"https:\/\/www.instagram.com\/euhtstpol\/\",\"https:\/\/www.linkedin.com\/school\/euhtstpol-barcelona\/mycompany\/\",\"https:\/\/es.pinterest.com\/euhtstpol\/\",\"https:\/\/www.youtube.com\/user\/EUHTStPOL1\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"hotel savoy Archivos - St. POL Hospitality &amp; Culinary Business School - Barcelona","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"hotel savoy Archivos - St. POL Hospitality &amp; Culinary Business School - Barcelona","og_url":"https:\/\/www.santpol.edu.es\/en\/blog\/hotel-savoy-ca-en\/","og_site_name":"St. POL Hospitality &amp; Culinary Business School - Barcelona","twitter_card":"summary_large_image","twitter_site":"@euhtstpol","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.santpol.edu.es\/en\/blog\/hotel-savoy-ca-en\/","url":"https:\/\/www.santpol.edu.es\/en\/blog\/hotel-savoy-ca-en\/","name":"hotel savoy Archivos - St. POL Hospitality &amp; Culinary Business School - Barcelona","isPartOf":{"@id":"https:\/\/www.santpol.edu.es\/#website"},"inLanguage":"en-US"},{"@type":"WebSite","@id":"https:\/\/www.santpol.edu.es\/#website","url":"https:\/\/www.santpol.edu.es\/","name":"St. POL Hospitality &amp; Culinary Business School - Barcelona","description":"St. POL Hospitality &amp; Culinary Business School - Barcelona","publisher":{"@id":"https:\/\/www.santpol.edu.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.santpol.edu.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.santpol.edu.es\/#organization","name":"St. POL Hospitality &amp; Culinary Business School - Barcelona","url":"https:\/\/www.santpol.edu.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.santpol.edu.es\/#\/schema\/logo\/image\/","url":"https:\/\/santpol.edu.es\/wp-content\/uploads\/2019\/09\/logoweb-santpol.jpg","contentUrl":"https:\/\/santpol.edu.es\/wp-content\/uploads\/2019\/09\/logoweb-santpol.jpg","width":324,"height":81,"caption":"St. POL Hospitality &amp; Culinary Business School - Barcelona"},"image":{"@id":"https:\/\/www.santpol.edu.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EUHTStPOL","https:\/\/x.com\/euhtstpol","https:\/\/www.instagram.com\/euhtstpol\/","https:\/\/www.linkedin.com\/school\/euhtstpol-barcelona\/mycompany\/","https:\/\/es.pinterest.com\/euhtstpol\/","https:\/\/www.youtube.com\/user\/EUHTStPOL1"]}]}},"_links":{"self":[{"href":"https:\/\/www.santpol.edu.es\/en\/wp-json\/wp\/v2\/tags\/9619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.santpol.edu.es\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.santpol.edu.es\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.santpol.edu.es\/en\/wp-json\/wp\/v2\/posts?tags=9619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}